{"id":231,"date":"2010-06-10T18:47:09","date_gmt":"2010-06-10T17:47:09","guid":{"rendered":"https:\/\/www.babystock.fr\/blog\/?p=231"},"modified":"2012-09-27T13:33:28","modified_gmt":"2012-09-27T11:33:28","slug":"le-ventre-de-maman-sophie-lebot","status":"publish","type":"post","link":"https:\/\/www.babystock.fr\/blog\/le-ventre-de-maman-sophie-lebot\/","title":{"rendered":"Le ventre de Maman de Sophie LEBOT"},"content":{"rendered":"<p>Une belle histoire, touchante et attachante. Elle raconte l&rsquo;arriv\u00e9e d&rsquo;un petit fr\u00e8re ou d&rsquo;une petite s\u0153ur dans la famille.<\/p>\n<p>Un livre qui vous aidera \u00e0 rassurer le plus grand de vos enfants sur la place qu&rsquo;occupera le nouveau \u00ab\u00a0ballon\/b\u00e9b\u00e9\u00a0\u00bb du ventre de Maman.<\/p>\n<p><!--more--><\/p>\n<p>Ses belles illustrations finissent de nous s\u00e9duire.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-229\" title=\"La grossesse racont\u00e9e aux enfants\" src=\"https:\/\/www.babystock.fr\/blog\/wp\/wp-content\/uploads\/2010\/06\/ventre2.jpg\" alt=\"La grossesse racont\u00e9e aux enfants\" width=\"338\" height=\"175\" srcset=\"https:\/\/www.babystock.fr\/blog\/wp\/wp-content\/uploads\/2010\/06\/ventre2.jpg 338w, https:\/\/www.babystock.fr\/blog\/wp\/wp-content\/uploads\/2010\/06\/ventre2-300x155.jpg 300w\" sizes=\"(max-width: 338px) 100vw, 338px\" \/><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-230\" title=\"J'ai un petit fr\u00e8re\" src=\"https:\/\/www.babystock.fr\/blog\/wp\/wp-content\/uploads\/2010\/06\/ventre3.jpg\" alt=\"J'ai un petit fr\u00e8re\" width=\"339\" height=\"178\" srcset=\"https:\/\/www.babystock.fr\/blog\/wp\/wp-content\/uploads\/2010\/06\/ventre3.jpg 339w, https:\/\/www.babystock.fr\/blog\/wp\/wp-content\/uploads\/2010\/06\/ventre3-300x157.jpg 300w\" sizes=\"(max-width: 339px) 100vw, 339px\" \/><\/p>\n<p>Mon petit dernier a ador\u00e9 et veut un petit fr\u00e8re &#8230; je fonce lui acheter un ballon !&#8230;<\/p>\n<p>Ce livre est disponible aux \u00e9ditions Lito au prix de <strong>7 euros<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Une belle histoire, touchante et attachante. Elle raconte l&rsquo;arriv\u00e9e d&rsquo;un petit fr\u00e8re ou d&rsquo;une petite s\u0153ur dans la famille. Un livre qui vous aidera \u00e0 rassurer le plus grand de vos enfants sur la place qu&rsquo;occupera le nouveau \u00ab\u00a0ballon\/b\u00e9b\u00e9\u00a0\u00bb du ventre de Maman.<\/p>\n","protected":false},"author":2,"featured_media":673,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"_links":{"self":[{"href":"https:\/\/www.babystock.fr\/blog\/wp-json\/wp\/v2\/posts\/231"}],"collection":[{"href":"https:\/\/www.babystock.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.babystock.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.babystock.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.babystock.fr\/blog\/wp-json\/wp\/v2\/comments?post=231"}],"version-history":[{"count":0,"href":"https:\/\/www.babystock.fr\/blog\/wp-json\/wp\/v2\/posts\/231\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.babystock.fr\/blog\/wp-json\/wp\/v2\/media\/673"}],"wp:attachment":[{"href":"https:\/\/www.babystock.fr\/blog\/wp-json\/wp\/v2\/media?parent=231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.babystock.fr\/blog\/wp-json\/wp\/v2\/categories?post=231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.babystock.fr\/blog\/wp-json\/wp\/v2\/tags?post=231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}